{"id":11945,"date":"2024-09-09T14:36:57","date_gmt":"2024-09-09T13:36:57","guid":{"rendered":"https:\/\/geneva.viacreative.co\/product\/tuba-sib-geneva-cardinal-jc\/"},"modified":"2025-12-21T08:25:59","modified_gmt":"2025-12-21T08:25:59","slug":"tuba-sib-geneva-cardinal-jc","status":"publish","type":"product","link":"https:\/\/genevainstruments.com\/it\/prodotto\/tuba-sib-geneva-cardinal-jc\/","title":{"rendered":"Tuba Sib &#8211; Geneva cardinal JC"},"content":{"rendered":"<h1 data-start=\"336\" data-end=\"394\">Geneva cardinal JC Tuba Sib<\/h1>\n<h2 data-start=\"336\" data-end=\"394\">Un tuba di livello mondiale progettato per il musicista serio<\/h2>\n<p data-start=\"396\" data-end=\"677\">Il <strong data-start=\"400\" data-end=\"429\">Geneva Cardinal JC Tuba<\/strong> \u00e8 il risultato di un quarto di secolo di continua ricerca e sviluppo. Costruito per i musicisti che richiedono un suono superiore, un&#8217;intonazione impeccabile e una lavorazione impeccabile, questo corno premium rappresenta l&#8217;apice delle ultime innovazioni degli strumenti in ottone di Geneva, puro lusso <\/p>\n<hr data-start=\"679\" data-end=\"682\">\n<p data-start=\"684\" data-end=\"700\"><strong>Caratteristiche principali<\/strong><\/p>\n<ul data-start=\"702\" data-end=\"1349\">\n<li data-start=\"702\" data-end=\"815\">\n<p data-start=\"704\" data-end=\"815\"><strong data-start=\"704\" data-end=\"732\">Canneggio Venturi Unico<\/strong><br data-start=\"732\" data-end=\"735\">Migliora la proiezione del suono e assicura un&#8217;esperienza di suono fluida e senza sforzo.<\/p>\n<\/li>\n<li data-start=\"817\" data-end=\"910\">\n<p data-start=\"819\" data-end=\"910\"><strong data-start=\"819\" data-end=\"841\">Campana Martellata a Mano<\/strong><br data-start=\"841\" data-end=\"844\">Realizzata con precisione artigianale per produrre un tono ricco e risonante.<\/p>\n<\/li>\n<\/ul>\n<ul>\n<li><strong data-start=\"819\" data-end=\"841\">Incisione a mano<\/strong><br data-start=\"841\" data-end=\"844\">Realizzato con precisione artigianale e con incisioni decorative del Grifone di Ginevra.<\/li>\n<\/ul>\n<ul data-start=\"702\" data-end=\"1349\">\n<li data-start=\"912\" data-end=\"989\">\n<p data-start=\"914\" data-end=\"989\"><strong data-start=\"914\" data-end=\"937\">Miscela di Metalli Su Misura<\/strong><br data-start=\"937\" data-end=\"940\">Progettata per durabilit\u00e0 e complessit\u00e0 tonale.<\/p>\n<\/li>\n<li data-start=\"991\" data-end=\"1087\">\n<p data-start=\"993\" data-end=\"1087\"><strong data-start=\"993\" data-end=\"1013\">Design Ergonomico<\/strong><br data-start=\"1013\" data-end=\"1016\">Comodo da impugnare e facile da controllare durante le esibizioni prolungate.<\/p>\n<\/li>\n<li data-start=\"1089\" data-end=\"1215\">\n<p data-start=\"1091\" data-end=\"1215\"><strong data-start=\"1091\" data-end=\"1112\">Design del livello di rotazione a paletta<\/strong><br data-start=\"1112\" data-end=\"1115\">Sviluppato in collaborazione con Glenn Van Looy per migliorare la risposta e la sensazione.<\/p>\n<\/li>\n<li data-start=\"1217\" data-end=\"1349\">\n<p data-start=\"1219\" data-end=\"1349\"><strong data-start=\"1219\" data-end=\"1252\">Placcatura in Nichel Nero Migliorata<\/strong><br data-start=\"1252\" data-end=\"1255\">Una nuova finitura elegante resa possibile dal nostro investimento in tecnologia di produzione di nuova generazione.<\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"1351\" data-end=\"1354\">\n<h2 data-start=\"1356\" data-end=\"1394\">Perch\u00e9 scegliere la Cardinal?<\/h2>\n<p data-start=\"1396\" data-end=\"1703\">Che tu sia un solista, un membro di un ensemble o un capobanda, la <strong data-start=\"1459\" data-end=\"1481\">gamma Cardinal<\/strong> offre la qualit\u00e0 e le prestazioni richieste dai professionisti di tutto il mondo. Utilizzato da importanti musicisti nel Regno Unito, in Europa, negli Stati Uniti, in Giappone e in Australia, questo strumento stabilisce un nuovo standard nella progettazione di ottoni artigianali. <\/p>\n<hr data-start=\"1705\" data-end=\"1708\">\n<h3 data-start=\"1710\" data-end=\"1726\">Test su strada &#8211; <a href=\"https:\/\/genevainstruments.com\/it\/prova-prima-di-acquistare\/\">prova prima di acquistare<\/a><\/h3>\n<p data-start=\"1728\" data-end=\"2030\">Se sei alla ricerca di un nuovo strumento e non hai provato il <strong data-start=\"1736\" data-end=\"1758\">Cardinal JC Tuba<\/strong> e desideri provarlo, compila il modulo di prova prima dell&#8217;acquisto, ci sono opzioni indipendentemente dal paese in cui risiedi.<\/p>\n<hr data-start=\"2303\" data-end=\"2306\">\n<h4 data-start=\"153\" data-end=\"194\"><strong>Ordina oggi stesso il tuo cardinal JC Tuba<\/strong><\/h4>\n<p data-start=\"196\" data-end=\"354\">Pronto a migliorare la tua performance? La <strong>Geneva<\/strong> <strong data-start=\"235\" data-end=\"257\">Cardinal Range<\/strong> offre una precisione musicale, una potenza e una maestria senza pari, apprezzate dai migliori musicisti di tutto il mondo. <\/p>\n<p data-start=\"356\" data-end=\"594\">Puoi <strong data-start=\"364\" data-end=\"404\">acquistare direttamente tramite questo negozio online<\/strong> oppure, se preferisci un approccio pi\u00f9 personale, soprattutto per chi si trova fuori dal Regno Unito, o hai bisogno di aiuto per scegliere il modello giusto, semplicemente <strong data-start=\"494\" data-end=\"573\">inviaci un&#8217;e-mail all&#8217;indirizzo <a class=\"decorated-link cursor-pointer\" href=\"mailto:info@genevainstruments.com\" rel=\"noopener\" data-start=\"508\" data-end=\"571\">info@genevainstruments.com<\/a><\/strong> per effettuare l&#8217;ordine.<\/p>\n<p data-start=\"596\" data-end=\"702\">Qualunque sia il modo in cui scegli, il nostro team \u00e8 qui per aiutarti a trovare la Cardinal perfetta per il tuo percorso musicale.<\/p>\n<hr data-start=\"2032\" data-end=\"2035\">\n<p data-start=\"2037\" data-end=\"2057\"><strong>Cosa dice il team di progettazione di Geneva<\/strong><\/p>\n<p>&#8220;Questa collaborazione unica tra Geneva e il virtuoso suonatore di tuba Joe Cook per produrre uno strumento che offra un suono pi\u00f9 grande e una maggiore proiezione senza distorsioni \u00e8 stata la sfida che ci siamo posti per questo prodotto.<\/p>\n<p><em>\u201cL&#8217;incorporazione risultante della campana Rose e della svasatura in nichel \u00e8 stata la soluzione perfetta a questa sfida, che ha creato uno strumento eccezionale che non ha paragoni nel mercato odierno.\u201d<\/em><\/p>\n<h4 style=\"text-align: center;\">\u201cCustodia rigida fornita con lo strumento.\u201d<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Geneva Instruments Tuba Sib &#8211; Geneva Cardinal JC.<\/p>\n","protected":false},"featured_media":11948,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[192],"product_cat":[595,403],"product_tag":[665],"class_list":{"0":"post-11945","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-geneva-instruments","7":"product_cat-modelli-per-artisti-geneva-cardinal","8":"product_cat-strumenti-geneva-cardinal","9":"product_tag-tuba-in-mib","10":"product_shipping_class-extra-large","11":"pa_range-strumenti-geneva-cardinal","12":"sales-flash-overlay","13":"woocommerce-text-align-left","14":"woocommerce-image-align-center","15":"do-quantity-buttons","17":"first","18":"onbackorder","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-variable"},"acf":[],"_links":{"self":[{"href":"https:\/\/genevainstruments.com\/it\/wp-json\/wp\/v2\/product\/11945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/genevainstruments.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/genevainstruments.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/genevainstruments.com\/it\/wp-json\/wp\/v2\/comments?post=11945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/genevainstruments.com\/it\/wp-json\/wp\/v2\/media\/11948"}],"wp:attachment":[{"href":"https:\/\/genevainstruments.com\/it\/wp-json\/wp\/v2\/media?parent=11945"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/genevainstruments.com\/it\/wp-json\/wp\/v2\/product_brand?post=11945"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/genevainstruments.com\/it\/wp-json\/wp\/v2\/product_cat?post=11945"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/genevainstruments.com\/it\/wp-json\/wp\/v2\/product_tag?post=11945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}